{"id":30920,"date":"2025-04-08T23:31:28","date_gmt":"2025-04-08T23:31:28","guid":{"rendered":"https:\/\/losangelestvradio.com\/?p=30920"},"modified":"2025-05-23T22:54:02","modified_gmt":"2025-05-23T22:54:02","slug":"mafia-de-los-pagares-defensa-publica-y-defensoria-del-pueblo-piden-informes-a-salud-y-educacion","status":"publish","type":"post","link":"https:\/\/losangelestvradio.com\/index.php\/2025\/04\/08\/mafia-de-los-pagares-defensa-publica-y-defensoria-del-pueblo-piden-informes-a-salud-y-educacion\/","title":{"rendered":"Mafia de los pagar\u00e9s: Defensa P\u00fablica y Defensor\u00eda del Pueblo piden informes a Salud y Educaci\u00f3n"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El&nbsp;<strong>Ministerio de la Defensa P\u00fablica<\/strong>&nbsp;y la&nbsp;<strong>Defensor\u00eda del Pueblo<\/strong>&nbsp;solicitaron informes a los ministerios de Educaci\u00f3n y Salud, como primera acci\u00f3n para atenci\u00f3n a v\u00edctimas de pagar\u00e9s irregulares, ante la falta de expedientes f\u00edsicos en los juzgados de paz.<\/h2>\n\n\n\n<p>Abril 08, 2025 07:45 p. m.&nbsp;\u2022&nbsp;<\/p>\n\n\n\n<p>El&nbsp;<strong>Ministerio de la Defensa P\u00fablica<\/strong>&nbsp;y la&nbsp;<strong>Defensor\u00eda del Pueblo<\/strong>&nbsp;iniciaron acciones conjuntas para atender a las v\u00edctimas de la estafa masiva por la emisi\u00f3n irregular de pagar\u00e9s.<\/p>\n\n\n\n<p>En ese sentido, ambas instituciones empezaron a trabajar en la conformaci\u00f3n de grupos de trabajo y la estrategia jur\u00eddica a ser implementada.<\/p>\n\n\n\n<p><em>Lea m\u00e1s:&nbsp;<\/em><a href=\"https:\/\/www.ultimahora.com\/mafia-de-pagares-saque-g-3-millones-y-pague-g-250-millones\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Mafia de pagar\u00e9s: \u201cSaqu\u00e9 G. 3 millones y pagu\u00e9 G. 250 millones\u201d<\/em><\/a><\/p>\n\n\n\n<p>Sin embargo, tropezaron con inconvenientes al no encontrar algunos expedientes f\u00edsicos en los juzgados de paz, lo que dificulta plantear una acci\u00f3n de forma inmediata.<\/p>\n\n\n\n<p>A ra\u00edz de esto, se busca individualizar a las personas afectadas, solicitando a los ministerios de Educaci\u00f3n y Salud, donde hay m\u00e1s afectados, mediante la Ley de Acceso a la Informaci\u00f3n P\u00fablica, que provean una lista de los funcionarios p\u00fablicos dependientes de la instituci\u00f3n, cuyos salarios se hallen gravados por embargos trabados en el marco de juicios ejecutivos promovidos en cualquiera de los juzgados.<\/p>\n\n\n\n<p>Los datos solicitados a los ministerios son nombre, c\u00e9dula, remuneraci\u00f3n total del funcionario, cuenta bancaria a trav\u00e9s de la cual percibe su remuneraci\u00f3n, juzgado que orden\u00f3 cada embargo, datos del expediente judicial, porcentaje del salario embargado, monto total descontado y cuenta judicial abierta en la cual depositan las sumas.<\/p>\n\n\n\n<p>Para las acciones legales, los afectados deber\u00e1n acercarse a solicitar que se les represente, teniendo en cuenta que no se puede intervenir de oficio en un proceso civil donde est\u00e1 afectado un patrimonio privado, seg\u00fan la norma procesal vigente.<\/p>\n\n\n\n<p>De igual manera, se est\u00e1 estudiando la estrategia en las acciones a tomar, entre ellas el art\u00edculo 38 de la Constituci\u00f3n Nacional, que reconoce el derecho a la defensa de los intereses difusos y la protecci\u00f3n al consumidor, que podr\u00eda permitir una acci\u00f3n colectiva, intentando una nulidad.<\/p>\n\n\n\n<p><em>Ent\u00e9rese m\u00e1s:&nbsp;<\/em><a href=\"https:\/\/www.ultimahora.com\/imputan-al-quinto-juez-que-estaria-vinculado-a-la-mafia-de-los-pagares\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Imputan al quinto juez que estar\u00eda vinculado a la mafia de los pagar\u00e9s<\/em><\/a><\/p>\n\n\n\n<p>\u201cEsto al considerar que hasta el momento se han identificado unas tres casu\u00edsticas diferentes o tipos de estafas con los pagar\u00e9s: pagar\u00e9s que se ejecutan m\u00e1s de una vez, otros donde las notificaciones nunca se realizaron, y la falsificaci\u00f3n de firmas; adem\u00e1s hay otros casos de expedientes que no existen en f\u00edsico, no se evidencian la existencia de esos expedientes\u201d, remarcaron.<\/p>\n\n\n\n<p>Entre tanto, tambi\u00e9n se toma en cuenta la cuesti\u00f3n de competencia territorial, es decir, si son todos de capital o si hay juzgados tambi\u00e9n en otras jurisdicciones del pa\u00eds.<\/p>\n\n\n\n<p>Las tareas del equipo de trabajo interinstitucional son lideradas por el defensor p\u00fablico, Javier Dejes\u00fas Esquivel y el defensor del pueblo, Rafael \u00c1vila.<\/p>\n\n\n\n<p>\u201cEn un esfuerzo por fortalecer la protecci\u00f3n de los derechos humanos en el \u00e1mbito judicial, ambas autoridades reafirman el compromiso de sus instituciones con la articulaci\u00f3n interinstitucional, destacando la necesidad de priorizar la atenci\u00f3n a las personas afectadas, garantizar el acceso a informaci\u00f3n clave del caso y promover una respuesta eficiente, integral y centrada en los derechos de las v\u00edctimas\u201d, recalcaron.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"javascript:window.print()\"><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;Ministerio de la Defensa P\u00fablica&nbsp;y la&nbsp;Defensor\u00eda del Pueblo&nbsp;solicitaron informes a los ministerios de Educaci\u00f3n y Salud, como primera acci\u00f3n para [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts\/30920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/comments?post=30920"}],"version-history":[{"count":1,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts\/30920\/revisions"}],"predecessor-version":[{"id":30922,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts\/30920\/revisions\/30922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/media\/30921"}],"wp:attachment":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/media?parent=30920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/categories?post=30920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/tags?post=30920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}