{"id":30238,"date":"2025-02-24T13:56:10","date_gmt":"2025-02-24T13:56:10","guid":{"rendered":"https:\/\/radiosuceso.com\/?p=30238"},"modified":"2025-05-23T22:54:04","modified_gmt":"2025-05-23T22:54:04","slug":"mec-insta-a-maestros-a-no-dar-tareas-para-la-casa-y-restringir-uso-de-celulares-en-aulas","status":"publish","type":"post","link":"https:\/\/losangelestvradio.com\/index.php\/2025\/02\/24\/mec-insta-a-maestros-a-no-dar-tareas-para-la-casa-y-restringir-uso-de-celulares-en-aulas\/","title":{"rendered":"MEC insta a maestros a no dar tareas para la casa y restringir uso de celulares en aulas"},"content":{"rendered":"<h3 class=\"Page-subHeadline\"><strong>Autoridades del Ministerio de Educaci\u00f3n y Ciencias instan a restringir el uso de tel\u00e9fonos celulares para alumnos menores de 15 a\u00f1os. La instituci\u00f3n tambi\u00e9n est\u00e1 en contra de enviar tareas para la casa a trav\u00e9s del celular. \u201cEl alumno debe aprender en la escuela\u201d, se\u00f1al\u00f3 el ministro Luis Ram\u00edrez.<\/strong><\/h3>\n<p>El ministro de Educaci\u00f3n y Ciencias (MEC), Luis Ram\u00edrez, inst\u00f3 a los maestros a establecer un l\u00edmite para la utilizaci\u00f3n de tel\u00e9fonos celulares en las aulas, para aprovechar la tecnolog\u00eda con fines pedag\u00f3gicos.<\/p>\n<p>\u201cNosotros pensamos que el tel\u00e9fono es un elemento que nos ayuda a aprender y como tal tiene su tiempo, tiene su etapa y tiene su modelo y su forma\u201d, expres\u00f3 el ministro, en comunicaci\u00f3n con radio Monumental 1080 AM.<\/p>\n<p>Para el secretario de Estado, a partir de los 15 a\u00f1os est\u00e1 permitido el uso de aparatos celulares con fines pedag\u00f3gicos.<\/p>\n<p>\u201cTodas las sociedades pedi\u00e1tricas nos hablan del perjuicio que ocasiona la pantalla m\u00e1s de dos horas de pantalla en la vida de los ni\u00f1os\u201d, argument\u00f3.<\/p>\n<p>Un grupo de padres, que no est\u00e1 de acuerdo con la postura de la instituci\u00f3n, refieren que es necesario el uso de los tel\u00e9fonos para una eventual emergencia que pueda ser comunicada por sus hijos, en el tiempo en que est\u00e9n en clases.<\/p>\n<p>Sin embargo, el ministro se\u00f1al\u00f3 que para esto deber\u00edan establecerse otros mecanismos.<\/p>\n<p>\u201cLa escuela tiene que tener las condiciones para hacer una comunicaci\u00f3n con los padres si el hijo tiene una necesidad o si la familia tiene una necesidad comunicarse. No deber\u00eda el ni\u00f1o tener su celular y si lo tiene se lo habilita cuando ya terminan las clases\u201d, sostuvo.<\/p>\n<h3>No a las tareas en la casa<\/h3>\n<p>Los que est\u00e1n a favor del uso de dispositivos en las aulas tambi\u00e9n argumentan que estos sirven para enviar tareas a los alumnos de forma directa.<\/p>\n<p>Sin embargo, el ministro de Educaci\u00f3n se mostr\u00f3 contrario a este tipo de pr\u00e1cticas.<\/p>\n<p>\u201cLa tarea est\u00e1 en una discusi\u00f3n para m\u00ed, porque yo no creo que el ni\u00f1o tenga que llevar ya tarea a la casa. Un ni\u00f1o tiene que ir a la casa para hacer otras cosas, para estar con sus padres, con su familia, con sus hermanos, para desarrollar, hacer deporte, para hacer otras actividades que en la escuela no pudo hacer\u201d, reflexion\u00f3.<\/p>\n<p>El secretario de Estado afirm\u00f3 que la casa no deber\u00eda convertirse en una \u201cescuela\u201d, donde la maestra sea la mam\u00e1.<\/p>\n<p>\u201cLa mam\u00e1 cumple una funci\u00f3n para la cual no est\u00e1 preparada, destruye su relaci\u00f3n con el hijo porque se pelea todo el tiempo por una tarea que ninguno de los dos muchas veces comprende\u201d, se\u00f1al\u00f3.<\/p>\n<p>El ministro explic\u00f3 que el \u201cmodelo de repetici\u00f3n\u201d que propone la t\u00e9cnica de llevar tareas a la casa ya qued\u00f3 en desuso en el marco de la ciencia de la educaci\u00f3n.<\/p>\n<p>\u201cNo por mucho repetir se va a mejorar. La tarea tiene que ser otra cosa que ayude a la comprensi\u00f3n, pero no repetir lo mismo\u201d, insisti\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades del Ministerio de Educaci\u00f3n y Ciencias instan a restringir el uso de tel\u00e9fonos celulares para alumnos menores de 15 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30347,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9],"tags":[10],"class_list":["post-30238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-portada"],"_links":{"self":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts\/30238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/comments?post=30238"}],"version-history":[{"count":1,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts\/30238\/revisions"}],"predecessor-version":[{"id":30348,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts\/30238\/revisions\/30348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/media\/30347"}],"wp:attachment":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/media?parent=30238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/categories?post=30238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/tags?post=30238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}