{"id":30053,"date":"2025-02-14T13:35:52","date_gmt":"2025-02-14T13:35:52","guid":{"rendered":"https:\/\/radiosuceso.com\/?p=30053"},"modified":"2025-05-23T22:54:20","modified_gmt":"2025-05-23T22:54:20","slug":"preocupa-la-baja-participacion-de-institutos-en-la-acreditacion-de-aneaes","status":"publish","type":"post","link":"https:\/\/losangelestvradio.com\/index.php\/2025\/02\/14\/preocupa-la-baja-participacion-de-institutos-en-la-acreditacion-de-aneaes\/","title":{"rendered":"Preocupa la baja participaci\u00f3n de institutos en la acreditaci\u00f3n de Aneaes"},"content":{"rendered":"<p class=\"paragraph\"><b>El presidente del consejo directivo de la Agencia Nacional de Evaluaci\u00f3n y Acreditaci\u00f3n de la Educaci\u00f3n Superior (Aneaes), Jos\u00e9 Duarte, exterioriz\u00f3 su preocupaci\u00f3n por la baja participaci\u00f3n de los institutos superiores en procesos de acreditaci\u00f3n.<\/b>\u00a0Dijo que est\u00e1 en marcha una campa\u00f1a de difusi\u00f3n que busca socializar ampliamente las carreras que est\u00e1n acreditadas por la Aneaes.<\/p>\n<div id=\"\" class=\"ads-box \">\n<div class=\"\">\n<div class=\"banner-cont\">\n<div class=\"banner\">\n<div class=\"ad-item\">\n<div class=\"adunitContainer\">\n<div id=\"ad-LN-SINGLE-01\" class=\"adBox\" data-google-query-id=\"CKTDyK2jw4sDFRtKuAQd1wAFmg\">\n<p class=\"paragraph\">\u201c<b>Tenemos 466 carreras actualmente acreditadas y solo el 2 % de estas carreras pertenecen a institutos superiores, mientras que el 98 % pertenece a universidades<\/b>. Recordemos que el subsistema de educaci\u00f3n superior en nuestro pa\u00eds no est\u00e1 conformado \u00fanicamente por universidades, sino tambi\u00e9n por institutos superiores, por institutos de formaci\u00f3n docente y por institutos t\u00e9cnicos profesionales\u201d, se\u00f1al\u00f3.<\/p>\n<p class=\"paragraph\">As\u00ed tambi\u00e9n, explic\u00f3 la diferencia entre una universidad y un instituto superior. El instituto superior en su ley de creaci\u00f3n\u00a0<b>est\u00e1 limitado<\/b>\u00a0a la implementaci\u00f3n de programas \u00fanicamente en el \u00e1rea de conocimiento por el que fueron creados. Mientras que la universidad tiene la\u00a0<b>autonom\u00eda<\/b>\u00a0para implementar carreras en diferentes \u00e1reas del conocimiento, conforme expres\u00f3.<\/p>\n<p class=\"paragraph\">\u201c<b>La preocupaci\u00f3n nuestra es que solamente tenemos ese porcentaje<\/b>\u00a0de institutos superiores que se presentan a procesos de acreditaci\u00f3n al mismo tiempo que hay muchos institutos superiores que en su ley de creaci\u00f3n tienen la posibilidad de implementar\u00a0<b>carreras de salud\u201d,<\/b>\u00a0manifest\u00f3.<\/p>\n<p class=\"paragraph\">Detall\u00f3 que hay varios casos de institutos superiores de ense\u00f1anza que tienen en su ley de creaci\u00f3n la posibilidad de implementar\u00a0<b>carreras de salud<\/b>\u00a0y que de hecho lo est\u00e1n aplicando, aunque \u201c<b>no han pasado por los procesos de evaluaci\u00f3n y acreditaci\u00f3n<\/b>\u201d de la Aneaes.<\/p>\n<div id=\"\" class=\"ads-box \">\n<div class=\"\">\n<div class=\"banner-cont\">\n<div class=\"banner\">\n<div class=\"ad-item\">\n<div class=\"adunitContainer\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"paragraph\">\u201cEstamos haciendo un trabajo de filtro de cada uno de ellos. Dependemos mucho, para hacer un trabajo de filtro, del catastro del Consejo Nacional de Educaci\u00f3n Superior, porque si bien tenemos a mano el buscador del Cones y sabemos que la informaci\u00f3n sobre la cantidad de carreras habilitadas es p\u00fablica, a\u00fan no tenemos acceso al car\u00e1cter activo o inactivo de las carreras habilitadas por el Cones\u201d, subray\u00f3.<\/p>\n<p class=\"paragraph\"><b>Destac\u00f3 el esfuerzo hecho por el titular del Consejo Nacional de Educaci\u00f3n Superior (Cones) y viceministro de Educaci\u00f3n Superior, Federico Mora, en este \u00e1mbito de la habilitaci\u00f3n de las carreras.<\/b><\/p>\n<p class=\"paragraph\">\u201cHay carreras que fueron habilitadas en alg\u00fan periodo, incluso antes del Cones, por el Consejo Nacional de Universidades, pero que hoy ya no est\u00e1n activas. Entonces, los datos que nos interesan son los de los institutos que tienen carreras activas para hacer el cruce\u201d, remarc\u00f3.<\/p>\n<p class=\"paragraph\">El director de la Aneaes aclar\u00f3 que esta instancia \u201cno tiene el poder sancionador\u201d, el cual recae en el Cones. \u201cEl Cones es el que tiene la facultad de intervenir, de suspender y de emitir sanciones. Nosotros somos una instituci\u00f3n evaluadora y acreditadora\u201d, enfatiz\u00f3.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del consejo directivo de la Agencia Nacional de Evaluaci\u00f3n y Acreditaci\u00f3n de la Educaci\u00f3n Superior (Aneaes), Jos\u00e9 Duarte, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9],"tags":[],"class_list":["post-30053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts\/30053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/comments?post=30053"}],"version-history":[{"count":1,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts\/30053\/revisions"}],"predecessor-version":[{"id":31036,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/posts\/30053\/revisions\/31036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/media?parent=30053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/categories?post=30053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/losangelestvradio.com\/index.php\/wp-json\/wp\/v2\/tags?post=30053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}